{"id":116341,"date":"2026-01-15T16:51:53","date_gmt":"2026-01-15T09:51:53","guid":{"rendered":"https:\/\/thisav.me\/hmn-711-ein-klassenkamerad-der-sein-herz-kennt-ich-bat-um-eine-pause-als-ich-zur-schule-ging\/"},"modified":"2026-01-15T16:51:53","modified_gmt":"2026-01-15T09:51:53","slug":"hmn-711-ein-klassenkamerad-der-sein-herz-kennt-ich-bat-um-eine-pause-als-ich-zur-schule-ging","status":"publish","type":"post","link":"https:\/\/thisav.me\/de\/hmn-711-ein-klassenkamerad-der-sein-herz-kennt-ich-bat-um-eine-pause-als-ich-zur-schule-ging\/","title":{"rendered":"HMN-711 Ein Klassenkamerad, der sein Herz kennt Ich bat um eine Pause, als ich zur Schule ging."},"content":{"rendered":"<p>HMN-711 Ein Klassenkamerad, der sein Herz kennt Jun Kasui Synopsis Jun Kasui Ein s\u00fc\u00dfes M\u00e4dchen, das mit einem \u00fcberf\u00fcllten Zug fahren muss, bis sie von ihren Klassenkameraden reibungslos arrangiert wird, bis sie s\u00fcchtig ist und wortlos zustimmt, seine Freundin zu sein.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqv2.xyz\/player\/index.php?data=7137debd45ae4d0ab9aa953017286b20\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HMN-711 Ein Klassenkamerad, der sein Herz kennt Jun Kasui Synopsis Jun Kasui Ein s\u00fc\u00dfes M\u00e4dchen, das mit einem \u00fcberf\u00fcllten Zug fahren muss, bis sie von ihren Klassenkameraden reibungslos arrangiert wird, bis sie s\u00fcchtig ist und wortlos zustimmt, seine Freundin zu sein. [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/thisav.me\/de\/hmn-711-ein-klassenkamerad-der-sein-herz-kennt-ich-bat-um-eine-pause-als-ich-zur-schule-ging\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":116251,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2577,106,107],"tags":[204,1182,149,2332,1185],"actors":[19959],"class_list":["post-116341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-av-zug","category-jav-ansehen","category-unzensiertes-leck","tag-cum-innen","tag-ein-gutes-madchen","tag-haarlos","tag-hmn-de","tag-versuchen","actors-jun-kasui-de"],"_links":{"self":[{"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/posts\/116341"}],"collection":[{"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/comments?post=116341"}],"version-history":[{"count":0,"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/posts\/116341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/media\/116251"}],"wp:attachment":[{"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/media?parent=116341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/categories?post=116341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/tags?post=116341"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/thisav.me\/de\/wp-json\/wp\/v2\/actors?post=116341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}