{"id":57731,"date":"2025-01-08T20:34:58","date_gmt":"2025-01-08T13:34:58","guid":{"rendered":"https:\/\/thisav.me\/juq-184-une-dirigeante-cruelle-demande-a-profiter-du-sexe-subordonne\/"},"modified":"2025-01-08T20:43:29","modified_gmt":"2025-01-08T13:43:29","slug":"juq-184-une-dirigeante-cruelle-demande-a-profiter-du-sexe-subordonne","status":"publish","type":"post","link":"https:\/\/thisav.me\/fr\/juq-184-une-dirigeante-cruelle-demande-a-profiter-du-sexe-subordonne\/","title":{"rendered":"JUQ-184 Une dirigeante cruelle demande \u00e0 profiter du sexe subordonn\u00e9"},"content":{"rendered":"<p>JUQ-184 Une dirigeante cruelle veut profiter du sexe subordonn\u00e9 Iioka Kanako Synopsis Kanako Iioka La patronne qui est s\u00e9rieuse au sujet de son travail appelle toujours ses subordonn\u00e9s \u00e0 bl\u00e2mer, jusqu\u2019au jour o\u00f9 elle doit rester en OT avec ses jeunes subordonn\u00e9s, elle ordonne \u00e0 ses subordonn\u00e9s de lui faire un massage, ce qui devient une relation passionn\u00e9e qu\u2019elle appr\u00e9cie volontiers ce travail.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqq.xyz\/player\/index.php?data=8a13dab3f5ec9e22d0d1495c8c85e436\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JUQ-184 Une dirigeante cruelle veut profiter du sexe subordonn\u00e9 Iioka Kanako Synopsis Kanako Iioka La patronne qui est s\u00e9rieuse au sujet de son travail appelle toujours ses subordonn\u00e9s \u00e0 bl\u00e2mer, jusqu\u2019au jour o\u00f9 elle doit rester en OT avec ses jeunes subordonn\u00e9s, elle ordonne \u00e0 ses subordonn\u00e9s de lui faire un massage, ce qui devient [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/thisav.me\/fr\/juq-184-une-dirigeante-cruelle-demande-a-profiter-du-sexe-subordonne\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":57681,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[250,98,96],"tags":[1939,4316,536],"actors":[19040],"class_list":["post-57731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bureau-audiovisuel","category-fuite-non-censuree","category-regarder-jav","tag-bas","tag-bonnet-h","tag-juq-fr","actors-iioka-kanako-fr"],"_links":{"self":[{"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/posts\/57731"}],"collection":[{"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/comments?post=57731"}],"version-history":[{"count":0,"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/posts\/57731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/media\/57681"}],"wp:attachment":[{"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/media?parent=57731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/categories?post=57731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/tags?post=57731"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/thisav.me\/fr\/wp-json\/wp\/v2\/actors?post=57731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}