{"id":22819,"count":5,"description":"","link":"https:\/\/thisav.me\/ja\/actor\/%e6%b0%b4%e7%80%ac-%e3%81%82%e3%81%8b%e3%82%8a\/","name":"\u6c34\u702c \u3042\u304b\u308a","slug":"%e6%b0%b4%e7%80%ac-%e3%81%82%e3%81%8b%e3%82%8a","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/thisav.me\/ja\/wp-json\/wp\/v2\/actors\/22819"}],"collection":[{"href":"https:\/\/thisav.me\/ja\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/thisav.me\/ja\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/thisav.me\/ja\/wp-json\/wp\/v2\/posts?actors=22819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}