{"id":23868,"count":1,"description":"","link":"https:\/\/thisav.me\/ko\/actor\/%ec%9c%a0%ec%9d%b4%eb%82%98-%eb%af%b8%ec%b8%a0%ed%82%a4\/","name":"\uc720\uc774\ub098 \ubbf8\uce20\ud0a4","slug":"%ec%9c%a0%ec%9d%b4%eb%82%98-%eb%af%b8%ec%b8%a0%ed%82%a4","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/actors\/23868"}],"collection":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/posts?actors=23868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}