{"id":42539,"count":1,"description":"","link":"https:\/\/thisav.me\/ko\/actor\/%ed%95%98%ec%95%bc%ec%8b%9c-%eb%a9%94%ec%9d%b4\/","name":"\ud558\uc57c\uc2dc \uba54\uc774","slug":"%ed%95%98%ec%95%bc%ec%8b%9c-%eb%a9%94%ec%9d%b4","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/actors\/42539"}],"collection":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/posts?actors=42539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}