{"id":43725,"count":0,"description":"","link":"https:\/\/thisav.me\/ko\/actor\/%eb%af%b8%ec%9d%b4%ec%bc%80-%ec%bd%94%ed%95%98%eb%a3%a8\/","name":"\ubbf8\uc774\ucf00 \ucf54\ud558\ub8e8","slug":"%eb%af%b8%ec%9d%b4%ec%bc%80-%ec%bd%94%ed%95%98%eb%a3%a8","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/actors\/43725"}],"collection":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/posts?actors=43725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}