{"id":5620,"count":19,"description":"","link":"https:\/\/thisav.me\/ko\/tag\/%eb%b0%b1%ec%9d%b8-%ec%86%8c%eb%85%80\/","name":"\ubc31\uc778 \uc18c\ub140","slug":"%eb%b0%b1%ec%9d%b8-%ec%86%8c%eb%85%80","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/tags\/5620"}],"collection":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thisav.me\/ko\/wp-json\/wp\/v2\/posts?tags=5620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}