{"id":4445,"count":2,"description":"","link":"https:\/\/thisav.me\/ms\/actor\/lulu-ms\/","name":"Lulu","slug":"lulu-ms","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/thisav.me\/ms\/wp-json\/wp\/v2\/actors\/4445"}],"collection":[{"href":"https:\/\/thisav.me\/ms\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/thisav.me\/ms\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/thisav.me\/ms\/wp-json\/wp\/v2\/posts?actors=4445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}