{"id":44655,"count":0,"description":"","link":"https:\/\/thisav.me\/zh-hant\/actor\/%e6%88%b0%e9%ac%a5%e6%88%91%e7%9a%84%e4%b8%96%e7%95%8c\/","name":"\u6230\u9b25\u6211\u7684\u4e16\u754c","slug":"%e6%88%b0%e9%ac%a5%e6%88%91%e7%9a%84%e4%b8%96%e7%95%8c","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/thisav.me\/zh-hant\/wp-json\/wp\/v2\/actors\/44655"}],"collection":[{"href":"https:\/\/thisav.me\/zh-hant\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/thisav.me\/zh-hant\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/thisav.me\/zh-hant\/wp-json\/wp\/v2\/posts?actors=44655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}